{"id":103715,"date":"2025-07-09T11:18:41","date_gmt":"2025-07-09T09:18:41","guid":{"rendered":"https:\/\/mediumaquamarine-tapir-850987.hostingersite.com\/?page_id=103715"},"modified":"2025-08-26T10:55:49","modified_gmt":"2025-08-26T08:55:49","slug":"aura","status":"publish","type":"page","link":"https:\/\/lineasette.com\/en\/aura\/","title":{"rendered":"Aura"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"103715\" class=\"elementor elementor-103715 elementor-101957\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b81db2 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"9b81db2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e83107\" data-id=\"2e83107\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31f6450 elementor-widget elementor-widget-heading\" data-id=\"31f6450\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aura<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d5ba93 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6d5ba93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-737cf3b\" data-id=\"737cf3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc4471a elementor-widget elementor-widget-text-editor\" data-id=\"cc4471a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Inspired by air, the Aura collection is defined by the movement of sinuous and straight lines, and by overlapping planes in a continuous bas-relief. It draws inspiration from the <em>Aura<\/em> mentioned by great poets such as Boccaccio, Dante, and Foscolo: a gentle breeze, like a fresh air that regenerates and caresses the forms.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b9b822 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8b9b822\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fe8354\" data-id=\"7fe8354\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3c17c8 elementor-widget elementor-widget-shortcode\" data-id=\"b3c17c8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"woocommerce columns-4 \"><ul class=\"products columns-4\">\n<li class=\"product type-product post-90222 status-publish first instock product_cat-centrepieces product_tag-aura-en product_tag-lovedesign-en has-post-thumbnail purchasable product-type-variable has-default-attributes\">\n\t<a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-centerpieces\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"380\" height=\"380\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VS990AB-380x380.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Aura centerpieces\" srcset=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VS990AB-380x380.jpg 380w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VS990AB-540x540.jpg 540w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VS990AB.jpg 1500w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VS990AB-768x768.jpg 768w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><h2 class=\"woocommerce-loop-product__title\">Aura centerpieces<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>110,00<\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>145,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-centerpieces\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_90222\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"90222\" data-product_sku=\"VS990\" aria-label=\"Select options for &ldquo;Aura centerpieces&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_90222\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:90222,&quot;item_id&quot;:&quot;VS990&quot;,&quot;item_name&quot;:&quot;Aura centerpieces&quot;,&quot;sku&quot;:&quot;VS990&quot;,&quot;price&quot;:105,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Centrepieces&quot;,&quot;id&quot;:&quot;VS990&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/lineasette.com\\\/en\\\/prodotto\\\/aura-centerpieces\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li>\n<li class=\"product type-product post-90223 status-publish instock product_cat-clocks product_tag-aura-en product_tag-lovedesign-en has-post-thumbnail purchasable product-type-variable has-default-attributes\">\n\t<a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-clock\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"380\" height=\"380\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/Y990_LA-380x380.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Aura clock\" srcset=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/Y990_LA-380x380.jpg 380w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/Y990_LA-540x540.jpg 540w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/Y990_LA.jpg 1500w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/Y990_LA-768x768.jpg 768w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><h2 class=\"woocommerce-loop-product__title\">Aura clock<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>170,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-clock\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_90223\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"90223\" data-product_sku=\"Y990\" aria-label=\"Select options for &ldquo;Aura clock&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_90223\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:90223,&quot;item_id&quot;:&quot;Y990&quot;,&quot;item_name&quot;:&quot;Aura clock&quot;,&quot;sku&quot;:&quot;Y990&quot;,&quot;price&quot;:170,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Clocks and Wall Artworks&quot;,&quot;id&quot;:&quot;Y990&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/lineasette.com\\\/en\\\/prodotto\\\/aura-clock\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:2,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li>\n<li class=\"product type-product post-90221 status-publish instock product_cat-vases product_tag-aura-en product_tag-lovedesign-en has-post-thumbnail purchasable product-type-variable has-default-attributes\">\n\t<a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-vases\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"380\" height=\"380\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VM990AB-380x380.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Aura vases\" srcset=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VM990AB-380x380.jpg 380w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VM990AB-540x540.jpg 540w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VM990AB.jpg 1500w, https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/VM990AB-768x768.jpg 768w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><h2 class=\"woocommerce-loop-product__title\">Aura vases<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>120,00<\/bdi><\/span> &ndash; <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>150,00<\/bdi><\/span><\/span>\n<\/a><a href=\"https:\/\/lineasette.com\/en\/prodotto\/aura-vases\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_90221\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"90221\" data-product_sku=\"VM990\" aria-label=\"Select options for &ldquo;Aura vases&rdquo;\" rel=\"nofollow\">Select options<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_90221\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:90221,&quot;item_id&quot;:&quot;VM990&quot;,&quot;item_name&quot;:&quot;Aura vases&quot;,&quot;sku&quot;:&quot;VM990&quot;,&quot;price&quot;:120,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Vases and Bottles&quot;,&quot;id&quot;:&quot;VM990&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/lineasette.com\\\/en\\\/prodotto\\\/aura-vases\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:3,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f5f86c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9f5f86c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-683e7f7\" data-id=\"683e7f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e0edf3 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6e0edf3\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_01.jpg\" alt=\"aura_01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_02.jpg\" alt=\"aura_02\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_03.jpg\" alt=\"aura_03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_04.jpg\" alt=\"aura_04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_05.jpg\" alt=\"aura_05\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_06.jpg\" alt=\"aura_06\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_07.jpg\" alt=\"aura_07\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_08.jpg\" alt=\"aura_08\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_09.jpg\" alt=\"aura_09\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_10.jpg\" alt=\"aura_10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_11.jpg\" alt=\"aura_11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_12.jpg\" alt=\"aura_12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_13.jpg\" alt=\"aura_13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/lineasette.com\/wp-content\/uploads\/2022\/01\/aura_14.jpg\" alt=\"aura_14\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8deb248 e-con-full e-flex e-con e-parent\" data-id=\"8deb248\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03a1c45 elementor-widget elementor-widget-video\" data-id=\"03a1c45\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/MSKEiv5oJsA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aura Inspired by air, the Aura collection is defined by the movement of sinuous and straight lines, and by overlapping planes in a continuous bas-relief. It draws inspiration from the Aura mentioned by great poets such as Boccaccio, Dante, and Foscolo: a gentle breeze, like a fresh air that regenerates and caresses the forms.<\/p>\n","protected":false},"author":214,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"iawp_total_views":25,"footnotes":""},"class_list":["post-103715","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/pages\/103715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/comments?post=103715"}],"version-history":[{"count":9,"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/pages\/103715\/revisions"}],"predecessor-version":[{"id":104882,"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/pages\/103715\/revisions\/104882"}],"wp:attachment":[{"href":"https:\/\/lineasette.com\/en\/wp-json\/wp\/v2\/media?parent=103715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}